{"id":10,"count":2,"description":"","link":"https:\/\/kerolic.net\/c\/category\/webtech\/","name":"Web\/Tech","slug":"webtech","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/kerolic.net\/c\/wp-json\/wp\/v2\/categories\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kerolic.net\/c\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/kerolic.net\/c\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/kerolic.net\/c\/wp-json\/wp\/v2\/posts?categories=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}